{"id":110643,"date":"2024-08-01T23:02:28","date_gmt":"2024-08-01T21:02:28","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=110643"},"modified":"2025-12-25T13:02:37","modified_gmt":"2025-12-25T12:02:37","slug":"maquina-de-costura-domestica-preta-modelo-128k-da-singer","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/pt\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/","title":{"rendered":"singer modelo 128K s\u00e9rie preto"},"featured_media":110651,"menu_order":631,"template":"","meta":{"_acf_changed":false},"museum-category":[1508,1248,1247,1498,1297],"class_list":["post-110643","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1910-1940-american","museum-category-american-domestic-machine-history-musuem-global","museum-category-american-made-machines-history-antique-museum-haarlem","museum-category-decade-american","museum-category-s-a-d-m-domestic-sewing-machines-american-musuem-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>singer model 128K series black - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/pt\/maquina-de-museu\/maquina-de-costura-domestica-preta-modelo-128k-da-singer\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"singer model 128K series black - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/pt\/maquina-de-museu\/maquina-de-costura-domestica-preta-modelo-128k-da-singer\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-25T12:02:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/08\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/\",\"name\":\"singer model 128K series black - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg\",\"datePublished\":\"2024-08-01T21:02:28+00:00\",\"dateModified\":\"2025-12-25T12:02:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Singer--128k-La-Vencedora-01-musuem-global-xs-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-128k-series-black-domestic-sewingmachine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"singer model 128K series black\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cantor modelo 128K s\u00e9rie preto - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/pt\/maquina-de-museu\/maquina-de-costura-domestica-preta-modelo-128k-da-singer\/","og_locale":"pt_PT","og_type":"article","og_title":"singer model 128K series black - Global International B.V.","og_url":"https:\/\/globalsew.com\/pt\/maquina-de-museu\/maquina-de-costura-domestica-preta-modelo-128k-da-singer\/","og_site_name":"Global International B.V.","article_modified_time":"2025-12-25T12:02:37+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/08\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/","url":"https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/","name":"cantor modelo 128K s\u00e9rie preto - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/08\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg","datePublished":"2024-08-01T21:02:28+00:00","dateModified":"2025-12-25T12:02:37+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/08\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/08\/Singer-128k-La-Vencedora-01-musuem-global-xs-web.jpg","width":1620,"height":1080,"caption":"Singer--128k-La-Vencedora-01-musuem-global-xs-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-128k-series-black-domestic-sewingmachine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"singer model 128K series black"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"M\u00e1quinas de costura industriais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/museum-machine\/110643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/media\/110651"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/media?parent=110643"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/museum-category?post=110643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}