{"id":108200,"date":"2024-04-11T01:10:58","date_gmt":"2024-04-10T23:10:58","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=108200"},"modified":"2024-12-26T00:46:18","modified_gmt":"2024-12-25T23:46:18","slug":"macousette-azul-brinquedo-costura-frech","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/pt\/museum-machine\/macousette-blue-toy-sewing-frech\/","title":{"rendered":"MaCousette Blue Toy"},"featured_media":108201,"menu_order":391,"template":"","meta":{"_acf_changed":false},"museum-category":[1522,1499,1231,1238,1401],"class_list":["post-108200","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1970-2000-french","museum-category-decade-french","museum-category-french-made-machines-sewing-musuem-global-machine-a-coudre-imca","museum-category-french-toy-machines","museum-category-m-f-t-m"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MaCousette Blue Toy - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/pt\/maquina-de-museu\/macousette-azul-brinquedo-costura-frech\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MaCousette Blue Toy - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/pt\/maquina-de-museu\/macousette-azul-brinquedo-costura-frech\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-25T23:46:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/\",\"name\":\"MaCousette Blue Toy - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg\",\"datePublished\":\"2024-04-10T23:10:58+00:00\",\"dateModified\":\"2024-12-25T23:46:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"MaCousette-03-01-france-toys-blue-musuem-global-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/macousette-blue-toy-sewing-frech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MaCousette Blue Toy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MaCousette Blue Toy - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/pt\/maquina-de-museu\/macousette-azul-brinquedo-costura-frech\/","og_locale":"pt_PT","og_type":"article","og_title":"MaCousette Blue Toy - Global International B.V.","og_url":"https:\/\/globalsew.com\/pt\/maquina-de-museu\/macousette-azul-brinquedo-costura-frech\/","og_site_name":"Global International B.V.","article_modified_time":"2024-12-25T23:46:18+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/","url":"https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/","name":"MaCousette Blue Toy - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg","datePublished":"2024-04-10T23:10:58+00:00","dateModified":"2024-12-25T23:46:18+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/MaCousette-03-01-france-toys-blue-musuem-global-web.jpg","width":1620,"height":1080,"caption":"MaCousette-03-01-france-toys-blue-musuem-global-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/macousette-blue-toy-sewing-frech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"MaCousette Blue Toy"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"M\u00e1quinas de costura industriais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/museum-machine\/108200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/media\/108201"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/media?parent=108200"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/pt\/wp-json\/wp\/v2\/museum-category?post=108200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}