{"id":114169,"date":"2025-11-09T17:53:05","date_gmt":"2025-11-09T16:53:05","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=114169"},"modified":"2025-11-09T18:04:57","modified_gmt":"2025-11-09T17:04:57","slug":"durkopp-model-1001-naaimachine-a-coudre-locksteek-duitsland-imca-museum-global","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/nl\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/","title":{"rendered":"D\u00fcrkopp model 1001 huishoudelijk"},"featured_media":114172,"menu_order":196,"template":"","meta":{"_acf_changed":false},"museum-category":[1527,1182,1500,1133,1132],"class_list":["post-114169","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1940-1970-de","museum-category-d-domestic-machines-german-made-machines-sewing","museum-category-decade-germany","museum-category-domestic-machines-german-made-machines","museum-category-german-made-machines-manufacture-sewing-global-musuem"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00fcrkopp model 1001 domestic - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/nl\/museummachine\/durkopp-model-1001-naaimachine-a-coudre-locksteek-duitsland-imca-museum-global\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00fcrkopp model 1001 domestic - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/nl\/museummachine\/durkopp-model-1001-naaimachine-a-coudre-locksteek-duitsland-imca-museum-global\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-09T17:04:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2025\/11\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/\",\"name\":\"D\u00fcrkopp model 1001 domestic - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg\",\"datePublished\":\"2025-11-09T16:53:05+00:00\",\"dateModified\":\"2025-11-09T17:04:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"d\u00fcrkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00fcrkopp model 1001 domestic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00fcrkopp model 1001 huishoudelijk - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/nl\/museummachine\/durkopp-model-1001-naaimachine-a-coudre-locksteek-duitsland-imca-museum-global\/","og_locale":"nl_NL","og_type":"article","og_title":"D\u00fcrkopp model 1001 domestic - Global International B.V.","og_url":"https:\/\/globalsew.com\/nl\/museummachine\/durkopp-model-1001-naaimachine-a-coudre-locksteek-duitsland-imca-museum-global\/","og_site_name":"Global International B.V.","article_modified_time":"2025-11-09T17:04:57+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2025\/11\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/","url":"https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/","name":"D\u00fcrkopp model 1001 huishoudelijk - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2025\/11\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg","datePublished":"2025-11-09T16:53:05+00:00","dateModified":"2025-11-09T17:04:57+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2025\/11\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2025\/11\/durkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web.jpg","width":1620,"height":1080,"caption":"d\u00fcrkopp-1001-01-01-domestic-german-grey-imca-musuem-global-s-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/durkopp-model-1001-domestic-sewing-machine-a-coudre-lockstitch-germany-imca-museum-global\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"D\u00fcrkopp model 1001 domestic"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industri\u00eble naaimachines","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-machine\/114169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/media\/114172"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/media?parent=114169"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-category?post=114169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}