{"id":108344,"date":"2024-04-16T00:08:44","date_gmt":"2024-04-15T22:08:44","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=108344"},"modified":"2024-04-16T00:08:44","modified_gmt":"2024-04-15T22:08:44","slug":"omega-poster","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/nl\/museum-machine\/omega-poster\/","title":{"rendered":"Omega-poster"},"featured_media":108345,"menu_order":785,"template":"","meta":{"_acf_changed":false},"museum-category":[1537,1539],"class_list":["post-108344","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-advertising","museum-category-poster"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Poster - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/nl\/museummachine\/omega-poster\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Poster - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/nl\/museummachine\/omega-poster\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/omega-01-posters-global-web-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2032\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/\",\"name\":\"Omega Poster - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/omega-01-posters-global-web-scaled.jpg\",\"datePublished\":\"2024-04-15T22:08:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/omega-01-posters-global-web-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/omega-01-posters-global-web-scaled.jpg\",\"width\":2032,\"height\":2560,\"caption\":\"omega-01-posters-global-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/omega-poster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Poster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Poster - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/nl\/museummachine\/omega-poster\/","og_locale":"nl_NL","og_type":"article","og_title":"Omega Poster - Global International B.V.","og_url":"https:\/\/globalsew.com\/nl\/museummachine\/omega-poster\/","og_site_name":"Global International B.V.","og_image":[{"width":2032,"height":2560,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/omega-01-posters-global-web-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/omega-poster\/","url":"https:\/\/globalsew.com\/museum-machine\/omega-poster\/","name":"Omega Poster - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/omega-poster\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/omega-poster\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/omega-01-posters-global-web-scaled.jpg","datePublished":"2024-04-15T22:08:44+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/omega-poster\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/omega-poster\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/globalsew.com\/museum-machine\/omega-poster\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/omega-01-posters-global-web-scaled.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/04\/omega-01-posters-global-web-scaled.jpg","width":2032,"height":2560,"caption":"omega-01-posters-global-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/omega-poster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"Omega Poster"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industri\u00eble naaimachines","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-machine\/108344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/media\/108345"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/media?parent=108344"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-category?post=108344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}