{"id":105153,"date":"2024-02-09T00:27:01","date_gmt":"2024-02-08T23:27:01","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=105153"},"modified":"2025-01-28T15:54:47","modified_gmt":"2025-01-28T14:54:47","slug":"grover-baker-verbeterde-shuttle","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/nl\/museum-machine\/grover-baker-improved-shuttle\/","title":{"rendered":"Grover &amp; Baker verbeterde shuttle"},"featured_media":103228,"menu_order":227,"template":"","meta":{"_acf_changed":false},"museum-category":[1504,1249,1247,1498,1306],"class_list":["post-105153","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1850-1880-american","museum-category-american-industrial-machines-sewing-museum-imca","museum-category-american-made-machines-history-antique-museum-haarlem","museum-category-decade-american","museum-category-g-a-i-m-industrial-grover-usa-american-sewing-machine-museum-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grover &amp; Baker improved shuttle - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/nl\/museummachine\/grover-baker-verbeterde-shuttle\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grover &amp; Baker improved shuttle - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/nl\/museummachine\/grover-baker-verbeterde-shuttle\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T14:54:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/12\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/\",\"name\":\"Grover & Baker improved shuttle - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg\",\"datePublished\":\"2024-02-08T23:27:01+00:00\",\"dateModified\":\"2025-01-28T14:54:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"grover-&-Baker-01-improved-shuttle-machine-industrial-musuem-global-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/grover-baker-improved-shuttle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grover &#038; Baker improved shuttle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grover &amp; Baker verbeterde shuttle - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/nl\/museummachine\/grover-baker-verbeterde-shuttle\/","og_locale":"nl_NL","og_type":"article","og_title":"Grover & Baker improved shuttle - Global International B.V.","og_url":"https:\/\/globalsew.com\/nl\/museummachine\/grover-baker-verbeterde-shuttle\/","og_site_name":"Global International B.V.","article_modified_time":"2025-01-28T14:54:47+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/12\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/","url":"https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/","name":"Grover &amp; Baker verbeterde shuttle - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/12\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg","datePublished":"2024-02-08T23:27:01+00:00","dateModified":"2025-01-28T14:54:47+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/12\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/12\/grover-Baker-01-inproved-shuttle-machine-industrial-musuem-global-web.jpg","width":1620,"height":1080,"caption":"grover-&-Baker-01-improved-shuttle-machine-industrial-musuem-global-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/grover-baker-improved-shuttle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"Grover &#038; Baker improved shuttle"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industri\u00eble naaimachines","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-machine\/105153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/media\/103228"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/media?parent=105153"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-category?post=105153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}