{"id":1439,"count":1,"description":"","link":"https:\/\/globalsew.com\/nl\/museum-category\/w-de-i-m\/","name":"W-DE-I-M","slug":"w-de-i-m","taxonomy":"museum-category","parent":1134,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>W-DE-I-M Archives - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/nl\/museumcategorie\/w-de-i-m\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W-DE-I-M Archives - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/nl\/museumcategorie\/w-de-i-m\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-category\\\/w-de-i-m\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-category\\\/w-de-i-m\\\/\",\"name\":\"W-DE-I-M Archives - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-category\\\/w-de-i-m\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-category\\\/w-de-i-m\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"German made Machines\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-category\\\/german-made-machines-manufacture-sewing-global-musuem\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"German Industrial machines\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-category\\\/industrial-machines-german-made-machines\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"W-DE-I-M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W-DE-I-M Archives - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/nl\/museumcategorie\/w-de-i-m\/","og_locale":"nl_NL","og_type":"article","og_title":"W-DE-I-M Archives - Global International B.V.","og_url":"https:\/\/globalsew.com\/nl\/museumcategorie\/w-de-i-m\/","og_site_name":"Global International B.V.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/globalsew.com\/museum-category\/w-de-i-m\/","url":"https:\/\/globalsew.com\/museum-category\/w-de-i-m\/","name":"W-DE-I-M Archief - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-category\/w-de-i-m\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-category\/w-de-i-m\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"German made Machines","item":"https:\/\/globalsew.com\/museum-category\/german-made-machines-manufacture-sewing-global-musuem\/"},{"@type":"ListItem","position":3,"name":"German Industrial machines","item":"https:\/\/globalsew.com\/museum-category\/industrial-machines-german-made-machines\/"},{"@type":"ListItem","position":4,"name":"W-DE-I-M"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industri\u00eble naaimachines","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-category\/1439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-category"}],"about":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/taxonomies\/museum-category"}],"up":[{"embeddable":true,"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-category\/1134"}],"wp:post_type":[{"href":"https:\/\/globalsew.com\/nl\/wp-json\/wp\/v2\/museum-machine?museum-category=1439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}