{"id":110494,"date":"2024-07-28T08:56:29","date_gmt":"2024-07-28T06:56:29","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=110494"},"modified":"2025-12-25T13:03:08","modified_gmt":"2025-12-25T12:03:08","slug":"singer-model-66-black-domestic-sewingmachine","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/fr\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/","title":{"rendered":"chanteuse mod\u00e8le 66 noir domestique"},"featured_media":110500,"menu_order":599,"template":"","meta":{"_acf_changed":false},"museum-category":[1508,1248,1247,1498,1297],"class_list":["post-110494","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1910-1940-american","museum-category-american-domestic-machine-history-musuem-global","museum-category-american-made-machines-history-antique-museum-haarlem","museum-category-decade-american","museum-category-s-a-d-m-domestic-sewing-machines-american-musuem-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>singer model 66 black domestic - Global International B.V.<\/title>\n<meta name=\"description\" content=\"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/fr\/machine-de-musee\/singer-model-66-black-domestic-sewingmachine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"singer model 66 black domestic - Global International B.V.\" \/>\n<meta property=\"og:description\" content=\"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/fr\/machine-de-musee\/singer-model-66-black-domestic-sewingmachine\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-25T12:03:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/07\/singer-66-01-05-domestic-black-musueum-global-xs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/\",\"name\":\"singer model 66 black domestic - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/singer-66-01-05-domestic-black-musueum-global-xs.jpg\",\"datePublished\":\"2024-07-28T06:56:29+00:00\",\"dateModified\":\"2025-12-25T12:03:08+00:00\",\"description\":\"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/singer-66-01-05-domestic-black-musueum-global-xs.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/singer-66-01-05-domestic-black-musueum-global-xs.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"singer-66-01-05-domestic-black-musueum-global-xs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-model-66-black-domestic-sewingmachine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"singer model 66 black domestic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"chanteur mod\u00e8le 66 noir domestique - Global International B.V.","description":"Les machines domestiques Singer ont fait leur apparition en 1851, rendant les machines \u00e0 coudre pratiques pour un usage domestique. Elles sont devenues populaires dans le monde entier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/fr\/machine-de-musee\/singer-model-66-black-domestic-sewingmachine\/","og_locale":"fr_FR","og_type":"article","og_title":"singer model 66 black domestic - Global International B.V.","og_description":"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide","og_url":"https:\/\/globalsew.com\/fr\/machine-de-musee\/singer-model-66-black-domestic-sewingmachine\/","og_site_name":"Global International B.V.","article_modified_time":"2025-12-25T12:03:08+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/07\/singer-66-01-05-domestic-black-musueum-global-xs.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/","url":"https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/","name":"chanteur mod\u00e8le 66 noir domestique - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/07\/singer-66-01-05-domestic-black-musueum-global-xs.jpg","datePublished":"2024-07-28T06:56:29+00:00","dateModified":"2025-12-25T12:03:08+00:00","description":"Les machines domestiques Singer ont fait leur apparition en 1851, rendant les machines \u00e0 coudre pratiques pour un usage domestique. Elles sont devenues populaires dans le monde entier.","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/07\/singer-66-01-05-domestic-black-musueum-global-xs.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/07\/singer-66-01-05-domestic-black-musueum-global-xs.jpg","width":1620,"height":1080,"caption":"singer-66-01-05-domestic-black-musueum-global-xs"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/singer-model-66-black-domestic-sewingmachine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"singer model 66 black domestic"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Machines \u00e0 coudre industrielles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/museum-machine\/110494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/media\/110500"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/media?parent=110494"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/museum-category?post=110494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}