{"id":105192,"date":"2024-02-10T19:04:31","date_gmt":"2024-02-10T18:04:31","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=105192"},"modified":"2026-01-08T18:54:11","modified_gmt":"2026-01-08T17:54:11","slug":"serie-petite-betty","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/fr\/museum-machine\/little-betty-series\/","title":{"rendered":"S\u00e9rie Little Betty jouet"},"featured_media":104569,"menu_order":345,"template":"","meta":{"_acf_changed":false},"museum-category":[1532,1533,1501,1545,1192],"class_list":["post-105192","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1910-1940-uk","museum-category-1940-1970-uk","museum-category-decade-united-kingdom","museum-category-manufacturers-series-uk","museum-category-united-kingdom-made-machines-history-uk-jones-newton-wilson-musuem-haarlem-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Little Betty Series toy - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/fr\/machine-de-musee\/serie-petite-betty\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Little Betty Series toy - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/fr\/machine-de-musee\/serie-petite-betty\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T17:54:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/\",\"name\":\"Little Betty Series toy - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg\",\"datePublished\":\"2024-02-10T18:04:31+00:00\",\"dateModified\":\"2026-01-08T17:54:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"little-betty-straco-01-01-toy-uk-line-up-musuem-global-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/little-betty-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Little Betty Series toy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jouet Little Betty Series - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/fr\/machine-de-musee\/serie-petite-betty\/","og_locale":"fr_FR","og_type":"article","og_title":"Little Betty Series toy - Global International B.V.","og_url":"https:\/\/globalsew.com\/fr\/machine-de-musee\/serie-petite-betty\/","og_site_name":"Global International B.V.","article_modified_time":"2026-01-08T17:54:11+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/little-betty-series\/","url":"https:\/\/globalsew.com\/museum-machine\/little-betty-series\/","name":"Jouet Little Betty Series - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/little-betty-series\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/little-betty-series\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg","datePublished":"2024-02-10T18:04:31+00:00","dateModified":"2026-01-08T17:54:11+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/little-betty-series\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/little-betty-series\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalsew.com\/museum-machine\/little-betty-series\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/little-betty-straco-01-01-toy-uk-line-up-musuem-global-web.jpg","width":1620,"height":1080,"caption":"little-betty-straco-01-01-toy-uk-line-up-musuem-global-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/little-betty-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"Little Betty Series toy"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Machines \u00e0 coudre industrielles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/museum-machine\/105192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/media\/104569"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/media?parent=105192"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/fr\/wp-json\/wp\/v2\/museum-category?post=105192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}