{"id":108255,"date":"2024-04-12T21:23:59","date_gmt":"2024-04-12T19:23:59","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=108255"},"modified":"2025-12-13T16:45:04","modified_gmt":"2025-12-13T15:45:04","slug":"weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/es\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/","title":{"rendered":"Weed m\u00e1quina de coser Co modelo General Favorite pedal dom\u00e9stico"},"featured_media":101506,"menu_order":711,"template":"","meta":{"_acf_changed":false},"museum-category":[1504,1248,1247,1498,1301],"class_list":["post-108255","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1850-1880-american","museum-category-american-domestic-machine-history-musuem-global","museum-category-american-made-machines-history-antique-museum-haarlem","museum-category-decade-american","museum-category-w-a-d-m-domestic-sewing-machine-american-musuem-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weed sewing machine Co model General Favorite treadle domestic - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/es\/maquina-museo\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weed sewing machine Co model General Favorite treadle domestic - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/es\/maquina-museo\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T15:45:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/weed-02-02-museum-global-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/\",\"name\":\"Weed sewing machine Co model General Favorite treadle domestic - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/weed-02-02-museum-global-web.jpg\",\"datePublished\":\"2024-04-12T19:23:59+00:00\",\"dateModified\":\"2025-12-13T15:45:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/weed-02-02-museum-global-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/weed-02-02-museum-global-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"weed-02-02-museum-global-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weed sewing machine Co model General Favorite treadle domestic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maquina de coser Co modelo General Favorite treadle domestic - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/es\/maquina-museo\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/","og_locale":"es_ES","og_type":"article","og_title":"Weed sewing machine Co model General Favorite treadle domestic - Global International B.V.","og_url":"https:\/\/globalsew.com\/es\/maquina-museo\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/","og_site_name":"Global International B.V.","article_modified_time":"2025-12-13T15:45:04+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/weed-02-02-museum-global-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/","url":"https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/","name":"Maquina de coser Co modelo General Favorite treadle domestic - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/weed-02-02-museum-global-web.jpg","datePublished":"2024-04-12T19:23:59+00:00","dateModified":"2025-12-13T15:45:04+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/weed-02-02-museum-global-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/weed-02-02-museum-global-web.jpg","width":1620,"height":1080,"caption":"weed-02-02-museum-global-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/weed-sewing-machine-company-general-favorite-treadle-sewingmachine-company-museum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"Weed sewing machine Co model General Favorite treadle domestic"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"M\u00e1quinas de coser industriales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/museum-machine\/108255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/media\/101506"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/media?parent=108255"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/museum-category?post=108255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}