{"id":106705,"date":"2024-03-16T17:06:05","date_gmt":"2024-03-16T16:06:05","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=106705"},"modified":"2024-04-08T21:38:34","modified_gmt":"2024-04-08T19:38:34","slug":"nahmaschinenteilewerke-studio-baquelita","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/es\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/","title":{"rendered":"N\u00e4hmaschinenteilewerke Studio Baquelita"},"featured_media":102276,"menu_order":428,"template":"","meta":{"_acf_changed":false},"museum-category":[1527,1500,1132,1135,1740],"class_list":["post-106705","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1940-1970-de","museum-category-decade-germany","museum-category-german-made-machines-manufacture-sewing-global-musuem","museum-category-german-toy-machines-sewing-museum-global","museum-category-n-de-t-m"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e4hmaschinenteilewerke Studio Bakelite - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/es\/maquina-museo\/nahmaschinenteilewerke-studio-baquelita\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e4hmaschinenteilewerke Studio Bakelite - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/es\/maquina-museo\/nahmaschinenteilewerke-studio-baquelita\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T19:38:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/\",\"name\":\"N\u00e4hmaschinenteilewerke Studio Bakelite - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Global_Logo.jpg\",\"datePublished\":\"2024-03-16T16:06:05+00:00\",\"dateModified\":\"2024-04-08T19:38:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Global_Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Global_Logo.jpg\",\"width\":801,\"height\":801},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteilewerke-studio-bakelite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"N\u00e4hmaschinenteilewerke Studio Bakelite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e4hmaschinenteilewerke Studio Bakelite - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/es\/maquina-museo\/nahmaschinenteilewerke-studio-baquelita\/","og_locale":"es_ES","og_type":"article","og_title":"N\u00e4hmaschinenteilewerke Studio Bakelite - Global International B.V.","og_url":"https:\/\/globalsew.com\/es\/maquina-museo\/nahmaschinenteilewerke-studio-baquelita\/","og_site_name":"Global International B.V.","article_modified_time":"2024-04-08T19:38:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/","url":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/","name":"N\u00e4hmaschinenteilewerke Studio Bakelite - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Global_Logo.jpg","datePublished":"2024-03-16T16:06:05+00:00","dateModified":"2024-04-08T19:38:34+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Global_Logo.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Global_Logo.jpg","width":801,"height":801},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteilewerke-studio-bakelite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"N\u00e4hmaschinenteilewerke Studio Bakelite"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"M\u00e1quinas de coser industriales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/museum-machine\/106705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/media\/102276"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/media?parent=106705"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/es\/wp-json\/wp\/v2\/museum-category?post=106705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}