{"id":108251,"date":"2024-04-12T21:01:42","date_gmt":"2024-04-12T19:01:42","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=108251"},"modified":"2025-12-25T13:28:11","modified_gmt":"2025-12-25T12:28:11","slug":"singer-12k-nahmaschine-haushaltsnahmaschine","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/de\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/","title":{"rendered":"Singer Modell 12k f\u00fcr den Hausgebrauch"},"featured_media":104310,"menu_order":548,"template":"","meta":{"_acf_changed":false},"museum-category":[1505,1248,1247,1498,1297],"class_list":["post-108251","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1880-1910-american","museum-category-american-domestic-machine-history-musuem-global","museum-category-american-made-machines-history-antique-museum-haarlem","museum-category-decade-american","museum-category-s-a-d-m-domestic-sewing-machines-american-musuem-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Singer model 12k domestic - Global International B.V.<\/title>\n<meta name=\"description\" content=\"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/de\/museumsmaschine\/singer-12k-nahmaschine-haushaltsnahmaschine\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Singer model 12k domestic - Global International B.V.\" \/>\n<meta property=\"og:description\" content=\"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/de\/museumsmaschine\/singer-12k-nahmaschine-haushaltsnahmaschine\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-25T12:28:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/Singer-12k-01museum-global-xl-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/\",\"name\":\"Singer model 12k domestic - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Singer-12k-01museum-global-xl-web.jpg\",\"datePublished\":\"2024-04-12T19:01:42+00:00\",\"dateModified\":\"2025-12-25T12:28:11+00:00\",\"description\":\"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Singer-12k-01museum-global-xl-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Singer-12k-01museum-global-xl-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Singer-12k-01museum-global-xl-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/singer-12k-sewing-machine-domestic-sewingmachine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Singer model 12k domestic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Singer Modell 12k f\u00fcr den Hausgebrauch \u2013 Global International B.V.","description":"Singer Haushaltsmaschinen wurden 1851 eingef\u00fchrt und machten N\u00e4hmaschinen f\u00fcr den Hausgebrauch praktisch. Sie wurden weltweit beliebt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/de\/museumsmaschine\/singer-12k-nahmaschine-haushaltsnahmaschine\/","og_locale":"de_DE","og_type":"article","og_title":"Singer model 12k domestic - Global International B.V.","og_description":"Singer domestic machines started in 1851, who made sewing machines practical for home use. They became popular worldwide","og_url":"https:\/\/globalsew.com\/de\/museumsmaschine\/singer-12k-nahmaschine-haushaltsnahmaschine\/","og_site_name":"Global International B.V.","article_modified_time":"2025-12-25T12:28:11+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/Singer-12k-01museum-global-xl-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/","url":"https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/","name":"Singer Modell 12k f\u00fcr den Hausgebrauch \u2013 Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/Singer-12k-01museum-global-xl-web.jpg","datePublished":"2024-04-12T19:01:42+00:00","dateModified":"2025-12-25T12:28:11+00:00","description":"Singer Haushaltsmaschinen wurden 1851 eingef\u00fchrt und machten N\u00e4hmaschinen f\u00fcr den Hausgebrauch praktisch. Sie wurden weltweit beliebt.","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/Singer-12k-01museum-global-xl-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/01\/Singer-12k-01museum-global-xl-web.jpg","width":1620,"height":1080,"caption":"Singer-12k-01museum-global-xl-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/singer-12k-sewing-machine-domestic-sewingmachine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"Singer model 12k domestic"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industrielle N\u00e4hmaschinen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine\/108251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/media\/104310"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/media?parent=108251"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-category?post=108251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}