{"id":106702,"date":"2024-03-16T16:56:19","date_gmt":"2024-03-16T15:56:19","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=106702"},"modified":"2025-10-12T14:41:51","modified_gmt":"2025-10-12T12:41:51","slug":"nahmaschinenteile-werke-grune-spielzeugnahmaschine-a-coudre-museum-global-imca","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/de\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/","title":{"rendered":"N\u00e4hmaschinenteilewerke Gr\u00fcnes Spielzeug"},"featured_media":106709,"menu_order":433,"template":"","meta":{"_acf_changed":false},"museum-category":[1527,1500,1132,1135,1740],"class_list":["post-106702","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1940-1970-de","museum-category-decade-germany","museum-category-german-made-machines-manufacture-sewing-global-musuem","museum-category-german-toy-machines-sewing-museum-global","museum-category-n-de-t-m"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e4hmaschinenteilewerke Green toy - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/de\/museumsmaschine\/nahmaschinenteile-werke-grune-spielzeugnahmaschine-a-coudre-museum-global-imca\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e4hmaschinenteilewerke Green toy - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/de\/museumsmaschine\/nahmaschinenteile-werke-grune-spielzeugnahmaschine-a-coudre-museum-global-imca\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T12:41:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/03\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/\",\"name\":\"N\u00e4hmaschinenteilewerke Green toy - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg\",\"datePublished\":\"2024-03-16T15:56:19+00:00\",\"dateModified\":\"2025-10-12T12:41:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"N\u00e4hmaschinenteilewerke-Dresden-01-musuem-global-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"N\u00e4hmaschinenteilewerke Green toy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e4hmaschinenteilewerke Gr\u00fcnes Spielzeug - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/de\/museumsmaschine\/nahmaschinenteile-werke-grune-spielzeugnahmaschine-a-coudre-museum-global-imca\/","og_locale":"de_DE","og_type":"article","og_title":"N\u00e4hmaschinenteilewerke Green toy - Global International B.V.","og_url":"https:\/\/globalsew.com\/de\/museumsmaschine\/nahmaschinenteile-werke-grune-spielzeugnahmaschine-a-coudre-museum-global-imca\/","og_site_name":"Global International B.V.","article_modified_time":"2025-10-12T12:41:51+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/03\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/","url":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/","name":"N\u00e4hmaschinenteilewerke Gr\u00fcnes Spielzeug - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/03\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg","datePublished":"2024-03-16T15:56:19+00:00","dateModified":"2025-10-12T12:41:51+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/03\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2024\/03\/Nahmaschinenteilewerke-Dresden-01-musuem-global-web.jpg","width":1620,"height":1080,"caption":"N\u00e4hmaschinenteilewerke-Dresden-01-musuem-global-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/nahmaschinenteile-werke-green-toy-sewing-machine-a-coudre-museum-global-imca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"N\u00e4hmaschinenteilewerke Green toy"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industrielle N\u00e4hmaschinen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine\/106702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/media\/106709"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/media?parent=106702"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-category?post=106702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}