{"id":106293,"date":"2024-03-03T01:13:08","date_gmt":"2024-03-03T00:13:08","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=106293"},"modified":"2025-10-12T14:40:10","modified_gmt":"2025-10-12T12:40:10","slug":"journaux-leblond-r-nahmaschine-a-coudre-franzosisch-imca-global-museum","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/de\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/","title":{"rendered":"Zeitungen \u2013 Modell R f\u00fcr den Hausgebrauch von Leblond"},"featured_media":102324,"menu_order":292,"template":"","meta":{"_acf_changed":false},"museum-category":[1518,1499,1232,1231,1350],"class_list":["post-106293","museum-machine","type-museum-machine","status-publish","has-post-thumbnail","hentry","museum-category-1850-1880-french","museum-category-decade-french","museum-category-french-domestic-machines-vintagen-machine-a-coudre-musuem-global-haarlem","museum-category-french-made-machines-sewing-musuem-global-machine-a-coudre-imca","museum-category-j-f-d-m"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journaux - leblond model R domestic - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/de\/museumsmaschine\/journaux-leblond-r-nahmaschine-a-coudre-franzosisch-imca-global-museum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journaux - leblond model R domestic - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/de\/museumsmaschine\/journaux-leblond-r-nahmaschine-a-coudre-franzosisch-imca-global-museum\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T12:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Journaux-leblond-modele-r-01-museum-global-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/\",\"name\":\"Journaux - leblond model R domestic - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Journaux-leblond-modele-r-01-museum-global-web.jpg\",\"datePublished\":\"2024-03-03T00:13:08+00:00\",\"dateModified\":\"2025-10-12T12:40:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Journaux-leblond-modele-r-01-museum-global-web.jpg\",\"contentUrl\":\"https:\\\/\\\/globalsew.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Journaux-leblond-modele-r-01-museum-global-web.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Journaux-leblond--modele-r-01-museum-global-web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Journaux &#8211; leblond model R domestic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journale - leblond model R domestic - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/de\/museumsmaschine\/journaux-leblond-r-nahmaschine-a-coudre-franzosisch-imca-global-museum\/","og_locale":"de_DE","og_type":"article","og_title":"Journaux - leblond model R domestic - Global International B.V.","og_url":"https:\/\/globalsew.com\/de\/museumsmaschine\/journaux-leblond-r-nahmaschine-a-coudre-franzosisch-imca-global-museum\/","og_site_name":"Global International B.V.","article_modified_time":"2025-10-12T12:40:10+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Journaux-leblond-modele-r-01-museum-global-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/","url":"https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/","name":"Journale - leblond model R domestic - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/#primaryimage"},"image":{"@id":"https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/#primaryimage"},"thumbnailUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Journaux-leblond-modele-r-01-museum-global-web.jpg","datePublished":"2024-03-03T00:13:08+00:00","dateModified":"2025-10-12T12:40:10+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/#primaryimage","url":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Journaux-leblond-modele-r-01-museum-global-web.jpg","contentUrl":"https:\/\/globalsew.com\/wp-content\/uploads\/2023\/11\/Journaux-leblond-modele-r-01-museum-global-web.jpg","width":1620,"height":1080,"caption":"Journaux-leblond--modele-r-01-museum-global-web"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/journaux-leblond-r-sewing-machine-a-coudre-french-imca-global-museum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"Journaux &#8211; leblond model R domestic"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industrielle N\u00e4hmaschinen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine\/106293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/media\/102324"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/media?parent=106293"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-category?post=106293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}