{"id":105415,"date":"2024-02-13T21:04:03","date_gmt":"2024-02-13T20:04:03","guid":{"rendered":"https:\/\/globalsew.com\/?post_type=museum-machine&#038;p=105415"},"modified":"2025-10-12T14:42:26","modified_gmt":"2025-10-12T12:42:26","slug":"neue-remington-verbesserte-nummer-04-nahmaschine-ein-coudre-gun-musuem-global","status":"publish","type":"museum-machine","link":"https:\/\/globalsew.com\/de\/museum-machine\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\/","title":{"rendered":"Neue Remington Improved Nr. 04 f\u00fcr den Hausgebrauch"},"featured_media":0,"menu_order":516,"template":"","meta":{"_acf_changed":false},"museum-category":[1504,1248,1247,1498,1296],"class_list":["post-105415","museum-machine","type-museum-machine","status-publish","hentry","museum-category-1850-1880-american","museum-category-american-domestic-machine-history-musuem-global","museum-category-american-made-machines-history-antique-museum-haarlem","museum-category-decade-american","museum-category-r-a-d-m-domestic-sewing-machine-history-usa-musuem-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Remington Improved No 04 domestic - Global International B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalsew.com\/de\/museumsmaschine\/neue-remington-verbesserte-nummer-04-nahmaschine-ein-coudre-gun-musuem-global\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Remington Improved No 04 domestic - Global International B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalsew.com\/de\/museumsmaschine\/neue-remington-verbesserte-nummer-04-nahmaschine-ein-coudre-gun-musuem-global\/\" \/>\n<meta property=\"og:site_name\" content=\"Global International B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T12:42:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\\\/\",\"url\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\\\/\",\"name\":\"New Remington Improved No 04 domestic - Global International B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\"},\"datePublished\":\"2024-02-13T20:04:03+00:00\",\"dateModified\":\"2025-10-12T12:42:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsew.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum\",\"item\":\"https:\\\/\\\/globalsew.com\\\/museum-machine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"New Remington Improved No 04 domestic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsew.com\\\/#website\",\"url\":\"https:\\\/\\\/globalsew.com\\\/\",\"name\":\"Global International B.V.\",\"description\":\"Industrial Sewing Machines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalsew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue Remington Improved No 04 domestic - Global International B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalsew.com\/de\/museumsmaschine\/neue-remington-verbesserte-nummer-04-nahmaschine-ein-coudre-gun-musuem-global\/","og_locale":"de_DE","og_type":"article","og_title":"New Remington Improved No 04 domestic - Global International B.V.","og_url":"https:\/\/globalsew.com\/de\/museumsmaschine\/neue-remington-verbesserte-nummer-04-nahmaschine-ein-coudre-gun-musuem-global\/","og_site_name":"Global International B.V.","article_modified_time":"2025-10-12T12:42:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalsew.com\/museum-machine\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\/","url":"https:\/\/globalsew.com\/museum-machine\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\/","name":"Neue Remington Improved No 04 domestic - Global International B.V.","isPartOf":{"@id":"https:\/\/globalsew.com\/#website"},"datePublished":"2024-02-13T20:04:03+00:00","dateModified":"2025-10-12T12:42:26+00:00","breadcrumb":{"@id":"https:\/\/globalsew.com\/museum-machine\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalsew.com\/museum-machine\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/globalsew.com\/museum-machine\/new-remington-improved-no-04-sewing-machine-a-coudre-gun-musuem-global\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/globalsew.com\/"},{"@type":"ListItem","position":2,"name":"Museum","item":"https:\/\/globalsew.com\/museum-machine\/"},{"@type":"ListItem","position":3,"name":"New Remington Improved No 04 domestic"}]},{"@type":"WebSite","@id":"https:\/\/globalsew.com\/#website","url":"https:\/\/globalsew.com\/","name":"Global International B.V.","description":"Industrielle N\u00e4hmaschinen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalsew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine\/105415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-machine"}],"about":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/types\/museum-machine"}],"wp:attachment":[{"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/media?parent=105415"}],"wp:term":[{"taxonomy":"museum-category","embeddable":true,"href":"https:\/\/globalsew.com\/de\/wp-json\/wp\/v2\/museum-category?post=105415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}